{"id":96,"date":"2016-09-16T13:16:01","date_gmt":"2016-09-16T12:16:01","guid":{"rendered":"http:\/\/www.lamapoll.de\/blog\/?p=96"},"modified":"2020-02-28T14:17:13","modified_gmt":"2020-02-28T12:17:13","slug":"quoten-fuer-terminfindung-anmeldungsformulare-panelanbindung-und-mehr","status":"publish","type":"post","link":"https:\/\/www.lamapoll.de\/blog\/quoten-fuer-terminfindung-anmeldungsformulare-panelanbindung-und-mehr\/","title":{"rendered":"Quoten: f\u00fcr Terminfindung, Anmeldungsformulare, Panelanbindung und mehr!"},"content":{"rendered":"<h3>Wobei helfen Quoten?<\/h3>\n<ul>\n<li>Sie ben\u00f6tigen eine bestimmte oder eine ausgeglichene Stichprobe: 500 m\u00e4nnliche und 500 weibliche Teilnehmer. Oder eine st\u00e4rkere Gewichtung bestimmter Einkommensgruppen. Oder mehr\/nur\/keine Teilnehmer mit bestimmten W\u00fcnsche, Vorlieben, Eigenschaften etc.<\/li>\n<li>Sie bieten die Anmeldung zu verschiedenen Veranstaltungen an. Sobald sich X Teilnehmer f\u00fcr eine Veranstaltung angemeldet haben, soll diese nicht mehr zur Verf\u00fcgung stehen.<\/li>\n<li>Sie bieten verschiedene Termine an, sobald ein Termin gebucht wurde, soll dieser nicht mehr zur Verf\u00fcgung stehen.<\/li>\n<\/ul>\n<h3>Wie stelle ich Quoten ein?<\/h3>\n<p>Eine ausf\u00fchrliche, bebilderte Anleitung zum Thema Quoten finden Sie in unserem <a href=\"https:\/\/help.lamapoll.de\/Features\/Erstellen\/Quoten-erstellen\/\">Helpdesk<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wobei helfen Quoten? Sie ben\u00f6tigen eine bestimmte oder eine ausgeglichene Stichprobe: 500 m\u00e4nnliche und 500 weibliche Teilnehmer. Oder eine st\u00e4rkere Gewichtung bestimmter Einkommensgruppen. Oder mehr\/nur\/keine Teilnehmer mit bestimmten W\u00fcnsche, Vorlieben, Eigenschaften etc. Sie bieten die Anmeldung zu verschiedenen Veranstaltungen an. Sobald sich X Teilnehmer f\u00fcr eine Veranstaltung angemeldet haben, soll diese nicht mehr zur Verf\u00fcgung [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":99,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,5],"tags":[8,30,31],"class_list":["post-96","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-feedbackmanagement","category-tipps-tricks","tag-lamapoll","tag-quoten","tag-umfragen"],"_links":{"self":[{"href":"https:\/\/www.lamapoll.de\/blog\/wp-json\/wp\/v2\/posts\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lamapoll.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lamapoll.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lamapoll.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lamapoll.de\/blog\/wp-json\/wp\/v2\/comments?post=96"}],"version-history":[{"count":7,"href":"https:\/\/www.lamapoll.de\/blog\/wp-json\/wp\/v2\/posts\/96\/revisions"}],"predecessor-version":[{"id":1660,"href":"https:\/\/www.lamapoll.de\/blog\/wp-json\/wp\/v2\/posts\/96\/revisions\/1660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lamapoll.de\/blog\/wp-json\/wp\/v2\/media\/99"}],"wp:attachment":[{"href":"https:\/\/www.lamapoll.de\/blog\/wp-json\/wp\/v2\/media?parent=96"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lamapoll.de\/blog\/wp-json\/wp\/v2\/categories?post=96"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lamapoll.de\/blog\/wp-json\/wp\/v2\/tags?post=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}